{"id":38852,"date":"2023-10-12T08:19:00","date_gmt":"2023-10-12T08:19:00","guid":{"rendered":"https:\/\/www.pegasuscadcam.com\/case-history\/fhl-kiriakidis-group-2\/"},"modified":"2025-07-08T15:18:09","modified_gmt":"2025-07-08T15:18:09","slug":"fhl-kiriakidis-group-2","status":"publish","type":"case-history","link":"https:\/\/pegasus.alemarlab.it\/es\/case_history\/fhl-kiriakidis-group-2\/","title":{"rendered":"FHL Kiriakidis Group"},"content":{"rendered":"<h2>Relato de la experiencia en el uso del software Pegasus cad-cam Stone.<\/h2>\n<p>F.H.L. I. KIRIAKIDIS Marbles &#8211; Granites S.A. se dedica a la extracci\u00f3n, elaboraci\u00f3n y comercio de m\u00e1rmol y granito desde 1991.<\/p>\n<p>Ofrece bloques, losas, baldosas, cortes a medida y proyectos totalmente personalizados. FHL Kiriakidis es una empresa griega l\u00edder en el sector del m\u00e1rmol blanco, ya que posee varias canteras tanto en Grecia como en el extranjero, de las que se extraen numerosos tipos de m\u00e1rmol blanco.<br \/>\nFHL sigue una l\u00ednea de producci\u00f3n vertical, que comienza con la excavaci\u00f3n de los bloques en sus canteras y termina con el procesamiento del material de \u00faltima generaci\u00f3n para el mercado mayorista o para productos a medida.<\/p>\n<p>En el mundo de la elaboraci\u00f3n del m\u00e1rmol, la precisi\u00f3n y la eficacia son elementos clave para garantizar resultados de alta calidad. En este contexto, el software Pegasus cad-cam surge como una soluci\u00f3n innovadora y fiable, dise\u00f1ada espec\u00edficamente para optimizar el proceso de producci\u00f3n, reducir los tiempos de mecanizado y mejorar el rendimiento en la industria de mecanizado del m\u00e1rmol.<br \/>\nPegasus cad-cam demuestra ser un producto de alta calidad y f\u00e1cil de usar, que ofrece soluciones que satisfacen las necesidades de su usuario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relato de la experiencia con el software Pegasus cad-cam Stone, arrojando luz sobre los avances logrados gracias a la perfecta integraci\u00f3n entre software y m\u00e1quinas.<\/p>\n","protected":false},"featured_media":38860,"template":"","categories":[39],"class_list":["post-38852","case-history","type-case-history","status-publish","has-post-thumbnail","hentry","category-stone-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/case-history\/38852"}],"collection":[{"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/case-history"}],"about":[{"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/types\/case-history"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/media\/38860"}],"wp:attachment":[{"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/media?parent=38852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pegasus.alemarlab.it\/es\/wp-json\/wp\/v2\/categories?post=38852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}